{"id":6875,"date":"2025-04-09T17:37:09","date_gmt":"2025-04-09T15:37:09","guid":{"rendered":"https:\/\/www.milleunascienza.com\/concorso-eureka-2025\/"},"modified":"2025-07-15T10:01:54","modified_gmt":"2025-07-15T08:01:54","slug":"concorso-eureka-2025","status":"publish","type":"post","link":"https:\/\/www.milleunascienza.com\/de\/concorso-eureka-2025\/","title":{"rendered":"Concorso Eureka 2025!"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p>Grazie al sostegno dell\u2019Ufficio Politiche Giovanili della Provincia Autonoma di Bolzano, anche quest\u2019anno vogliamo offrire un\u2019occasione unica per stimolare la curiosit\u00e0, la creativit\u00e0 e il pensiero critico ai pi\u00f9 giovani, mettendoli in contatto con il mondo della ricerca e della divulgazione scientifica.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:42;line-height:var(--awb-typography1-line-height);\">Il concorso<\/h3><\/div><div class=\"fusion-text fusion-text-2\"><p>Invita i giovani a esplorare la scienza attraverso l\u2019arte, la tecnologia e la creativit\u00e0. Il concorso \u00e8 rivolto a ragazze e ragazzi dagli 8 ai 18 anni, che potranno partecipare con un\u2019invenzione, un\u2019opera d\u2019arte o un video legati al tema della scienza.<\/p>\n<p>Che meraviglia la scienza! Il tema di quest\u2019anno. Dall\u2019immensamente piccolo all\u2019immensamente grande!<\/p>\n<p>Dalle cellule microscopiche alle galassie pi\u00f9 lontane, dai pi\u00f9 piccoli dettagli ai giganti che popolano il nostro pianeta, dai microscopi alle astronavi: ogni scoperta nel mondo della scienza \u00e8 fonte di stupore! Il tema di quest\u2019anno invita tutti a osservare il mondo con occhi diversi, attenti e creativi, per raccogliere e raccontare agli altri ci\u00f2 che c\u2019\u00e8 di pi\u00f9 affascinante nel mondo che ci circonda attraverso un\u2019opera creativa!<\/p>\n<\/div><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:42;line-height:var(--awb-typography1-line-height);\">Chi pu\u00f2 partecipare<\/h3><\/div><div class=\"fusion-text fusion-text-3\"><p>Il concorso \u00e8 aperto a <strong>ragazze e ragazzi dagli 8 ai 18 anni della Provincia di Bolzano<\/strong>, suddivisi in due categorie:<\/p>\n<ul>\n<li>8-12 anni<\/li>\n<li>13-18 anni<\/li>\n<\/ul>\n<p>Si pu\u00f2 partecipare singolarmente o in gruppo (fino a tre partecipanti) oppure come classe scolastica sotto la guida di un insegnante.<\/p>\n<\/div><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:42;line-height:var(--awb-typography1-line-height);\">Cosa si pu\u00f2 presentare?<\/h3><\/div><div class=\"fusion-text fusion-text-4\"><p>I partecipanti possono presentare:<\/p>\n<ul>\n<li>un\u2019invenzione (un progetto scientifico o tecnologico con un prototipo realizzato)<\/li>\n<li>un\u2019opera d\u2019arte (disegno, scultura, modello 3D)<\/li>\n<li>un video (racconto visivo di massimo 5 minuti)<\/li>\n<\/ul>\n<p>E\u2019 necessario allegare una descrizione dettagliata dell\u2019idea, spiegando il procedimento e i materiali utilizzati e fotografie o video che mostino il progetto!<\/p>\n<\/div><div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:42;line-height:var(--awb-typography1-line-height);\">Come partecipare?<\/h3><\/div><div class=\"fusion-text fusion-text-5\"><p>L\u2019iscrizione \u00e8 gratuita! Basta compilare il <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSc9Rz9EhXfPGxycWGjb1iRqdCN4PiZ8i4h7y_cwN-QFbkdySw\/viewform\" target=\"_blank\" rel=\"noopener\"><strong>MODULO ONLINE<\/strong><\/a> e inviare la documentazione richiesta.<\/p>\n<p>Il centro di cultura giovanile TesLab \u00e8 a disposizione per supportare i partecipanti nella realizzazione dei materiali!<\/p>\n<ul>\n<li><strong>SCADENZA INVIO PROGETTI<\/strong>: 30 settembre 2025<\/li>\n<li><strong>PREMIAZIONE<\/strong>: Durante il Festival Le Mille e una Scienza<\/li>\n<\/ul>\n<\/div><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-three\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;\"><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:42;line-height:var(--awb-typography1-line-height);\">Cosa si vince?<\/h3><\/div><div class=\"fusion-text fusion-text-6\"><p>Tutti riceveranno un riconoscimento speciale per il loro impegno! Il podio sar\u00e0 premiato con strumentazione scientifica e tecnologica, kit STEAM per esperimenti e scoperte, occasioni per approfondire il mondo della scienza.<\/p>\n<p>Inoltre verr\u00e0 assegnata una menzione speciale dall\u2019Ufficio Ricerca Scientifica della Provincia Autonoma di Bolzano.<\/p>\n<p>Una giuria di esperti selezioner\u00e0 i migliori progetti sulla base dell\u2019originalit\u00e0, della creativit\u00e0 e della capacit\u00e0 di comunicare il concetto scientifico.<\/p>\n<p>Sei curioso, creativo, e ami esplorare il mondo che ti circonda? Hai un\u2019idea geniale che unisce scienza e arte? Eureka! \u00e8 l\u2019occasione perfetta per metterti in gioco!<\/p>\n<p><strong>Info e contatti<\/strong>: <a href=\"mailto:eureka.concorso@gmail.com\">eureka.concorso@gmail.com<\/a><\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Siamo felici di annunciarvi il ritorno di EUREKA! il concorso di idee scientifiche del Festival \u201cLe Mille e una Scienza\u201d, il primo festival della scienza dedicato a bambine e bambini, ragazze e ragazzi!<\/p>\n","protected":false},"author":1,"featured_media":5051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[],"class_list":["post-6875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-de"],"_links":{"self":[{"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/posts\/6875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/comments?post=6875"}],"version-history":[{"count":1,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/posts\/6875\/revisions"}],"predecessor-version":[{"id":7354,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/posts\/6875\/revisions\/7354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/media\/5051"}],"wp:attachment":[{"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/media?parent=6875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/categories?post=6875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.milleunascienza.com\/de\/wp-json\/wp\/v2\/tags?post=6875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}